{"id":7138,"date":"2022-12-02T12:15:44","date_gmt":"2022-12-02T11:15:44","guid":{"rendered":"https:\/\/www.voiptiger.com\/docs\/how-can-i-access-my-sip-account-options\/"},"modified":"2022-12-02T12:24:38","modified_gmt":"2022-12-02T11:24:38","password":"","slug":"options-de-compte-sip","status":"publish","type":"docs","link":"https:\/\/www.voiptiger.com\/fr\/docs\/options-de-compte-sip\/","title":{"rendered":"Options de compte SIP"},"content":{"rendered":"<h1>Acc\u00e9der aux options du compte SIP<\/h1>\n<p>Pour acc\u00e9der aux options du compte SIP, cliquez sur l&rsquo;ic\u00f4ne des param\u00e8tres :<br \/>\n<img loading=\"lazy\" decoding=\"async\" width=\"1135\" height=\"405\" class=\"alignnone wp-image-7127 size-full\" src=\"https:\/\/www.voiptiger.com\/wp-content\/uploads\/2022\/12\/Pasted-8.png\" srcset=\"https:\/\/www.voiptiger.com\/wp-content\/uploads\/2022\/12\/Pasted-8.png 1135w, https:\/\/www.voiptiger.com\/wp-content\/uploads\/2022\/12\/Pasted-8-1024x365.png 1024w, https:\/\/www.voiptiger.com\/wp-content\/uploads\/2022\/12\/Pasted-8-768x274.png 768w, https:\/\/www.voiptiger.com\/wp-content\/uploads\/2022\/12\/Pasted-8-320x114.png 320w, https:\/\/www.voiptiger.com\/wp-content\/uploads\/2022\/12\/Pasted-8-480x171.png 480w, https:\/\/www.voiptiger.com\/wp-content\/uploads\/2022\/12\/Pasted-8-800x285.png 800w, https:\/\/www.voiptiger.com\/wp-content\/uploads\/2022\/12\/Pasted-8-640x228.png 640w, https:\/\/www.voiptiger.com\/wp-content\/uploads\/2022\/12\/Pasted-8-400x143.png 400w, https:\/\/www.voiptiger.com\/wp-content\/uploads\/2022\/12\/Pasted-8-367x131.png 367w\" sizes=\"auto, (max-width: 1135px) 100vw, 1135px\" \/><\/p>\n<h1>Options de compte SIP<\/h1>\n<p><img loading=\"lazy\" decoding=\"async\" width=\"1131\" height=\"538\" class=\"alignnone wp-image-7133 size-full\" src=\"https:\/\/www.voiptiger.com\/wp-content\/uploads\/2022\/12\/Pasted-10.png\" srcset=\"https:\/\/www.voiptiger.com\/wp-content\/uploads\/2022\/12\/Pasted-10.png 1131w, https:\/\/www.voiptiger.com\/wp-content\/uploads\/2022\/12\/Pasted-10-1024x487.png 1024w, https:\/\/www.voiptiger.com\/wp-content\/uploads\/2022\/12\/Pasted-10-768x365.png 768w, https:\/\/www.voiptiger.com\/wp-content\/uploads\/2022\/12\/Pasted-10-320x152.png 320w, https:\/\/www.voiptiger.com\/wp-content\/uploads\/2022\/12\/Pasted-10-480x228.png 480w, https:\/\/www.voiptiger.com\/wp-content\/uploads\/2022\/12\/Pasted-10-800x381.png 800w, https:\/\/www.voiptiger.com\/wp-content\/uploads\/2022\/12\/Pasted-10-640x304.png 640w, https:\/\/www.voiptiger.com\/wp-content\/uploads\/2022\/12\/Pasted-10-400x190.png 400w, https:\/\/www.voiptiger.com\/wp-content\/uploads\/2022\/12\/Pasted-10-367x175.png 367w\" sizes=\"auto, (max-width: 1131px) 100vw, 1131px\" \/><\/p>\n<h3>Nom du compte<\/h3>\n<p>Nom convivial de votre compte.<\/p>\n<h3>Mot de passe<\/h3>\n<p>Vous pouvez modifier le mot de passe SIP ici si n\u00e9cessaire.<\/p>\n<h3>Pr\u00e9fixe du pays<\/h3>\n<p>Ici, vous pouvez d\u00e9finir le pr\u00e9fixe de votre pays afin de pouvoir passer des appels locaux.<br \/>\nExemple : si vous d\u00e9finissez +31, vous pouvez composer un num\u00e9ro local n\u00e9erlandais sans commencer le +31 ou le 0031, comme le 0102671621.<br \/>\nPour la Belgique, vous pouvez laisser ce champ vide car par d\u00e9faut les appels belges locaux sont accept\u00e9s.<\/p>\n<h3>Transf\u00e9rer l&rsquo;appel vers mon num\u00e9ro (mobile)<\/h3>\n<p>Transf\u00e9rer l&rsquo;appel apr\u00e8s x secondes vers le num\u00e9ro souhait\u00e9.<br \/>\nEntrez votre num\u00e9ro (mobile) au format international.<\/p>\n<h3>Messagerie vocale si occup\u00e9<\/h3>\n<p>Renvoyez l&rsquo;appelant vers votre messagerie vocale si vous \u00eates d\u00e9j\u00e0 en communication.<\/p>\n<h3>Messagerie vocale si pas de r\u00e9ponse<\/h3>\n<p>Envoyer l&rsquo;appelant vers la messagerie vocale si l&rsquo;appel n&rsquo;est pas r\u00e9pondu apr\u00e8s x secondes.<\/p>\n<h3>Recevoir des messages vocaux par e-mail<\/h3>\n<p>Remplissez l&rsquo;adresse e-mail \u00e0 laquelle les messages vocaux seront envoy\u00e9s.<br \/>\nVous recevrez le message vocal en pi\u00e8ce jointe sous forme de fichier audio.<\/p>\n<h3>Supprimer les messages vocaux apr\u00e8s r\u00e9ception par e-mail<\/h3>\n<p>Utilisez cette option si vous ne souhaitez pas conserver les messages vocaux sur notre serveur. Normalement, vous cochez cette option lorsque vous utilisez la messagerie vocale pour envoyer un e-mail.<\/p>\n<h3>Langue messagerie vocale<\/h3>\n<p>La langue des options de vos messages vocaux.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Acc\u00e9der aux options du compte SIP Pour acc\u00e9der aux options du compte SIP, cliquez sur l&rsquo;ic\u00f4ne des param\u00e8tres : Options de compte SIP Nom du compte Nom convivial de votre compte. Mot de passe Vous pouvez modifier le mot de passe SIP ici si n\u00e9cessaire. Pr\u00e9fixe du pays Ici, vous pouvez d\u00e9finir le pr\u00e9fixe de [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"footnotes":""},"doc_category":[182],"doc_tag":[],"class_list":["post-7138","docs","type-docs","status-publish","hentry","doc_category-pbx-virtuel"],"year_month":"2026-07","word_count":261,"total_views":0,"reactions":{"happy":0,"normal":0,"sad":0},"author_info":{"name":"admin","author_nicename":"admin","author_url":"https:\/\/www.voiptiger.com\/fr\/author\/admin\/"},"doc_category_info":[{"term_name":"PBX virtuel","term_url":"https:\/\/www.voiptiger.com\/fr\/docs-category\/pbx-virtuel\/"}],"doc_tag_info":[],"_links":{"self":[{"href":"https:\/\/www.voiptiger.com\/fr\/wp-json\/wp\/v2\/docs\/7138","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.voiptiger.com\/fr\/wp-json\/wp\/v2\/docs"}],"about":[{"href":"https:\/\/www.voiptiger.com\/fr\/wp-json\/wp\/v2\/types\/docs"}],"author":[{"embeddable":true,"href":"https:\/\/www.voiptiger.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.voiptiger.com\/fr\/wp-json\/wp\/v2\/comments?post=7138"}],"version-history":[{"count":2,"href":"https:\/\/www.voiptiger.com\/fr\/wp-json\/wp\/v2\/docs\/7138\/revisions"}],"predecessor-version":[{"id":7142,"href":"https:\/\/www.voiptiger.com\/fr\/wp-json\/wp\/v2\/docs\/7138\/revisions\/7142"}],"wp:attachment":[{"href":"https:\/\/www.voiptiger.com\/fr\/wp-json\/wp\/v2\/media?parent=7138"}],"wp:term":[{"taxonomy":"doc_category","embeddable":true,"href":"https:\/\/www.voiptiger.com\/fr\/wp-json\/wp\/v2\/doc_category?post=7138"},{"taxonomy":"doc_tag","embeddable":true,"href":"https:\/\/www.voiptiger.com\/fr\/wp-json\/wp\/v2\/doc_tag?post=7138"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}