{"id":7203,"date":"2022-12-06T15:09:32","date_gmt":"2022-12-06T14:09:32","guid":{"rendered":"https:\/\/www.voiptiger.com\/docs\/how-can-i-configure-business-hours\/"},"modified":"2022-12-06T15:19:38","modified_gmt":"2022-12-06T14:19:38","password":"","slug":"comment-configurer-les-heures-douverture","status":"publish","type":"docs","link":"https:\/\/www.voiptiger.com\/fr\/docs\/comment-configurer-les-heures-douverture\/","title":{"rendered":"Comment configurer les heures d&rsquo;ouverture"},"content":{"rendered":"<p>\u00c0 l&rsquo;aide des heures d&rsquo;ouverture, vous pouvez d\u00e9finir comment g\u00e9rer les appels entrants en fonction de vos heures d&rsquo;ouverture.<\/p>\n<h3>Ajout d&rsquo;itin\u00e9raires<\/h3>\n<p>Afin d&rsquo;utiliser les heures d&rsquo;ouverture, vous aurez besoin d&rsquo;au moins 2 routes:<br \/>\n&#8211; le premier route traitera les appels pendant les heures ouvrables<br \/>\n&#8211; la deuxi\u00e8me route traitera les appels en dehors des heures ouvrables<\/p>\n<p>Exemple:<br \/>\n<img loading=\"lazy\" decoding=\"async\" width=\"1137\" height=\"413\" class=\"alignnone wp-image-7186 size-full\" src=\"https:\/\/www.voiptiger.com\/wp-content\/uploads\/2022\/12\/Pasted-15.png\" srcset=\"https:\/\/www.voiptiger.com\/wp-content\/uploads\/2022\/12\/Pasted-15.png 1137w, https:\/\/www.voiptiger.com\/wp-content\/uploads\/2022\/12\/Pasted-15-1024x372.png 1024w, https:\/\/www.voiptiger.com\/wp-content\/uploads\/2022\/12\/Pasted-15-768x279.png 768w, https:\/\/www.voiptiger.com\/wp-content\/uploads\/2022\/12\/Pasted-15-320x116.png 320w, https:\/\/www.voiptiger.com\/wp-content\/uploads\/2022\/12\/Pasted-15-480x174.png 480w, https:\/\/www.voiptiger.com\/wp-content\/uploads\/2022\/12\/Pasted-15-800x291.png 800w, https:\/\/www.voiptiger.com\/wp-content\/uploads\/2022\/12\/Pasted-15-640x232.png 640w, https:\/\/www.voiptiger.com\/wp-content\/uploads\/2022\/12\/Pasted-15-400x145.png 400w, https:\/\/www.voiptiger.com\/wp-content\/uploads\/2022\/12\/Pasted-15-367x133.png 367w\" sizes=\"auto, (max-width: 1137px) 100vw, 1137px\" \/><\/p>\n<p>La route \u00ab\u00a0Open\u00a0\u00bb traitera les appels pendant les heures ouvrables :<br \/>\nLorsque le num\u00e9ro +3219610320 est appel\u00e9 pendant les heures ouvrables, une file d&rsquo;attente d&rsquo;appels sonne , si personne ne d\u00e9croche apr\u00e8s 55 secondes, l&rsquo;appel est transf\u00e9r\u00e9 au +3212345678.<\/p>\n<p>Route \u00ab\u00a0Closed\u00a0\u00bb traitera les appels en dehors des heures d&rsquo;ouverture :<br \/>\nLorsque le num\u00e9ro +3219610320 est appel\u00e9 en dehors des heures d&rsquo;ouverture, un fichier son est jou\u00e9 : \u00ab\u00a0Bonjour, nous sommes actuellement ferm\u00e9s. Nos bureaux sont ouverts de\/jusqu&rsquo;\u00e0, veuillez nous laisser un message\u00a0\u00bb.<\/p>\n<h3>Configurer les heures d&rsquo;ouverture<\/h3>\n<p>Dans le menu PBX , s\u00e9lectionnez Horaires d&rsquo;ouverture :<br \/>\n<img loading=\"lazy\" decoding=\"async\" width=\"1201\" height=\"350\" class=\"alignnone wp-image-7190 size-full\" src=\"https:\/\/www.voiptiger.com\/wp-content\/uploads\/2022\/12\/Pasted-16.png\" srcset=\"https:\/\/www.voiptiger.com\/wp-content\/uploads\/2022\/12\/Pasted-16.png 1201w, https:\/\/www.voiptiger.com\/wp-content\/uploads\/2022\/12\/Pasted-16-1024x298.png 1024w, https:\/\/www.voiptiger.com\/wp-content\/uploads\/2022\/12\/Pasted-16-768x224.png 768w, https:\/\/www.voiptiger.com\/wp-content\/uploads\/2022\/12\/Pasted-16-320x93.png 320w, https:\/\/www.voiptiger.com\/wp-content\/uploads\/2022\/12\/Pasted-16-480x140.png 480w, https:\/\/www.voiptiger.com\/wp-content\/uploads\/2022\/12\/Pasted-16-800x233.png 800w, https:\/\/www.voiptiger.com\/wp-content\/uploads\/2022\/12\/Pasted-16-640x187.png 640w, https:\/\/www.voiptiger.com\/wp-content\/uploads\/2022\/12\/Pasted-16-400x117.png 400w, https:\/\/www.voiptiger.com\/wp-content\/uploads\/2022\/12\/Pasted-16-367x107.png 367w\" sizes=\"auto, (max-width: 1201px) 100vw, 1201px\" \/><\/p>\n<p>Cliquez ensuite sur ajouter pour ajouter une nouvelle entr\u00e9e d&rsquo;heures d&rsquo;ouverture.<\/p>\n<p>Dans l&rsquo;exemple ci-dessous, nous avons d\u00e9fini les r\u00e8gles comme suit :<\/p>\n<p>Nom : choisissez un nom convivial<br \/>\nFuseau horaire : s\u00e9lectionnez votre fuseau horaire<\/p>\n<p>Le lundi, jeudi et vendredi, l&rsquo;entreprise est \u00ab\u00a0ouverte\u00a0\u00bb de 09h00 \u00e0 12h00 et de 13h00 \u00e0 18h00.<br \/>\nPendant ces p\u00e9riodes, la route \u00ab\u00a0Open\u00a0\u00bb traitera les appels. En dehors de ces heures, la route \u00ab\u00a0Closed\u00a0\u00bb traitera les appels.<\/p>\n<p>Le mardi, l&rsquo;entreprise est toujours disponible. Cela signifie que toute la route du mardi \u00ab\u00a0Open\u00a0\u00bb traitera les appels.<\/p>\n<p>Le vendredi, samedi et dimanche l&rsquo;entreprise est ferm\u00e9e. Les appels seront trait\u00e9s par route \u00ab\u00a0Closed\u00a0\u00bb.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" width=\"966\" height=\"955\" class=\"alignnone wp-image-7196 size-full\" src=\"https:\/\/www.voiptiger.com\/wp-content\/uploads\/2022\/12\/Pasted-18.png\" srcset=\"https:\/\/www.voiptiger.com\/wp-content\/uploads\/2022\/12\/Pasted-18.png 966w, https:\/\/www.voiptiger.com\/wp-content\/uploads\/2022\/12\/Pasted-18-768x759.png 768w, https:\/\/www.voiptiger.com\/wp-content\/uploads\/2022\/12\/Pasted-18-320x316.png 320w, https:\/\/www.voiptiger.com\/wp-content\/uploads\/2022\/12\/Pasted-18-480x475.png 480w, https:\/\/www.voiptiger.com\/wp-content\/uploads\/2022\/12\/Pasted-18-800x791.png 800w, https:\/\/www.voiptiger.com\/wp-content\/uploads\/2022\/12\/Pasted-18-640x633.png 640w, https:\/\/www.voiptiger.com\/wp-content\/uploads\/2022\/12\/Pasted-18-400x395.png 400w, https:\/\/www.voiptiger.com\/wp-content\/uploads\/2022\/12\/Pasted-18-367x363.png 367w\" sizes=\"auto, (max-width: 966px) 100vw, 966px\" \/><\/p>\n<p>Avant d&rsquo;appuyer sur ENREGISTRER, n&rsquo;oubliez pas de choisir le num\u00e9ro entrant auquel les heures d&rsquo;ouverture doivent \u00eatre appliqu\u00e9es sous \u00ab\u00a0Activer les heures d&rsquo;ouverture\u00a0\u00bb.<br \/>\nNormalement, ce num\u00e9ro doit \u00eatre le m\u00eame que celui attribu\u00e9 \u00e0 votre route \u00ab\u00a0Open\u00a0\u00bb.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00c0 l&rsquo;aide des heures d&rsquo;ouverture, vous pouvez d\u00e9finir comment g\u00e9rer les appels entrants en fonction de vos heures d&rsquo;ouverture. Ajout d&rsquo;itin\u00e9raires Afin d&rsquo;utiliser les heures d&rsquo;ouverture, vous aurez besoin d&rsquo;au moins 2 routes: &#8211; le premier route traitera les appels pendant les heures ouvrables &#8211; la deuxi\u00e8me route traitera les appels en dehors des heures [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"footnotes":""},"doc_category":[182],"doc_tag":[],"class_list":["post-7203","docs","type-docs","status-publish","hentry","doc_category-pbx-virtuel"],"year_month":"2026-07","word_count":299,"total_views":0,"reactions":{"happy":0,"normal":0,"sad":0},"author_info":{"name":"admin","author_nicename":"admin","author_url":"https:\/\/www.voiptiger.com\/fr\/author\/admin\/"},"doc_category_info":[{"term_name":"PBX virtuel","term_url":"https:\/\/www.voiptiger.com\/fr\/docs-category\/pbx-virtuel\/"}],"doc_tag_info":[],"_links":{"self":[{"href":"https:\/\/www.voiptiger.com\/fr\/wp-json\/wp\/v2\/docs\/7203","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.voiptiger.com\/fr\/wp-json\/wp\/v2\/docs"}],"about":[{"href":"https:\/\/www.voiptiger.com\/fr\/wp-json\/wp\/v2\/types\/docs"}],"author":[{"embeddable":true,"href":"https:\/\/www.voiptiger.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.voiptiger.com\/fr\/wp-json\/wp\/v2\/comments?post=7203"}],"version-history":[{"count":2,"href":"https:\/\/www.voiptiger.com\/fr\/wp-json\/wp\/v2\/docs\/7203\/revisions"}],"predecessor-version":[{"id":7207,"href":"https:\/\/www.voiptiger.com\/fr\/wp-json\/wp\/v2\/docs\/7203\/revisions\/7207"}],"wp:attachment":[{"href":"https:\/\/www.voiptiger.com\/fr\/wp-json\/wp\/v2\/media?parent=7203"}],"wp:term":[{"taxonomy":"doc_category","embeddable":true,"href":"https:\/\/www.voiptiger.com\/fr\/wp-json\/wp\/v2\/doc_category?post=7203"},{"taxonomy":"doc_tag","embeddable":true,"href":"https:\/\/www.voiptiger.com\/fr\/wp-json\/wp\/v2\/doc_tag?post=7203"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}